{"id":60808,"date":"2025-09-23T01:51:58","date_gmt":"2025-09-22T23:51:58","guid":{"rendered":"https:\/\/www.galeriebd.com\/product\/\/krimi-page-41\/"},"modified":"2026-02-10T03:53:36","modified_gmt":"2026-02-10T02:53:36","slug":"krimi-page-41","status":"publish","type":"product","link":"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/","title":{"rendered":"Krimi"},"content":{"rendered":"<p>Sale of original comic art (original drawing) by French comic book artist Alex W. Inker.<\/p>\n<p>Published in the graphic novel <em>Krimi,<\/em> a thriller that immerses us in 1930s Germany in the company of director Fritz Lang. A magnificent graphic homage to German Expressionism.<\/p>\n<p>Page 41.<\/p>\n<p>Done with blue pencil, ink, charcoal, white Posca pen, and white watercolor ink.<\/p>\n<p>\u00a9Inker\/Sarbacane<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sale of original comic art by Alex W. Inker. Original comic art from graphic novel Krimi, page 41.<\/p>\n","protected":false},"featured_media":60809,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[212],"product_tag":[],"class_list":["post-60808","product","type-product","status-publish","has-post-thumbnail","artists-alex-w-inker-en","product_cat-unclassified","pa_annee-de-publication-2025-en","pa_technique-blue-pencil","pa_technique-charcoal","pa_technique-ink","first","instock","purchasable","product-type-simple"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Alex W. INKER - Krimi - Page 41 - Galerie de la Bande Dessinee<\/title>\n<meta name=\"description\" content=\"Sale of original comic art by Alex W. Inker. Original comic art from graphic novel Krimi, page 41.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alex W. INKER - Krimi - Page 41 - Galerie de la Bande Dessinee\" \/>\n<meta property=\"og:description\" content=\"Sale of original comic art by Alex W. Inker. Original comic art from graphic novel Krimi, page 41.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/\" \/>\n<meta property=\"og:site_name\" content=\"Galerie de la Bande Dessinee\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GaleriedelaBandeDessinee\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T02:53:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.galeriebd.com\/wp-content\/uploads\/2025\/09\/Alex-inker-Krimi-dessins-originaux-bd-planche-41.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1353\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@comicartfactory\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/product\\\/alex-w-inker\\\/krimi-page-41\\\/\",\"url\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/product\\\/alex-w-inker\\\/krimi-page-41\\\/\",\"name\":\"Alex W. INKER - Krimi - Page 41 - Galerie de la Bande Dessinee\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/product\\\/alex-w-inker\\\/krimi-page-41\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/product\\\/alex-w-inker\\\/krimi-page-41\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.galeriebd.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Alex-inker-Krimi-dessins-originaux-bd-planche-41.jpg\",\"datePublished\":\"2025-09-22T23:51:58+00:00\",\"dateModified\":\"2026-02-10T02:53:36+00:00\",\"description\":\"Sale of original comic art by Alex W. Inker. Original comic art from graphic novel Krimi, page 41.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/product\\\/alex-w-inker\\\/krimi-page-41\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/product\\\/alex-w-inker\\\/krimi-page-41\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/product\\\/alex-w-inker\\\/krimi-page-41\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.galeriebd.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Alex-inker-Krimi-dessins-originaux-bd-planche-41.jpg\",\"contentUrl\":\"https:\\\/\\\/www.galeriebd.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/Alex-inker-Krimi-dessins-originaux-bd-planche-41.jpg\",\"width\":1353,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/product\\\/alex-w-inker\\\/krimi-page-41\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/shop\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Unclassified\",\"item\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/categorie-produit\\\/unclassified\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Krimi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/\",\"name\":\"La Galerie de la Bande Dessin\u00e9e\",\"description\":\"Vente de dessins originaux et de planches de BD\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/#organization\",\"name\":\"La Galerie de la Bande Dessin\u00e9e\",\"url\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.galeriebd.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/GalerieBD-logo-RVB-3pos-e1664285120235.jpg\",\"contentUrl\":\"https:\\\/\\\/www.galeriebd.com\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/GalerieBD-logo-RVB-3pos-e1664285120235.jpg\",\"width\":1400,\"height\":812,\"caption\":\"La Galerie de la Bande Dessin\u00e9e\"},\"image\":{\"@id\":\"https:\\\/\\\/www.galeriebd.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GaleriedelaBandeDessinee\",\"https:\\\/\\\/x.com\\\/comicartfactory\",\"https:\\\/\\\/www.instagram.com\\\/galeriebd\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCN3x23zPeXNcd0zkbi5dPeg\\\/videos\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alex W. INKER - Krimi - Page 41 - Galerie de la Bande Dessinee","description":"Sale of original comic art by Alex W. Inker. Original comic art from graphic novel Krimi, page 41.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/","og_locale":"en_US","og_type":"article","og_title":"Alex W. INKER - Krimi - Page 41 - Galerie de la Bande Dessinee","og_description":"Sale of original comic art by Alex W. Inker. Original comic art from graphic novel Krimi, page 41.","og_url":"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/","og_site_name":"Galerie de la Bande Dessinee","article_publisher":"https:\/\/www.facebook.com\/GaleriedelaBandeDessinee","article_modified_time":"2026-02-10T02:53:36+00:00","og_image":[{"width":1353,"height":1920,"url":"https:\/\/www.galeriebd.com\/wp-content\/uploads\/2025\/09\/Alex-inker-Krimi-dessins-originaux-bd-planche-41.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@comicartfactory","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/","url":"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/","name":"Alex W. INKER - Krimi - Page 41 - Galerie de la Bande Dessinee","isPartOf":{"@id":"https:\/\/www.galeriebd.com\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/#primaryimage"},"image":{"@id":"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/#primaryimage"},"thumbnailUrl":"https:\/\/www.galeriebd.com\/wp-content\/uploads\/2025\/09\/Alex-inker-Krimi-dessins-originaux-bd-planche-41.jpg","datePublished":"2025-09-22T23:51:58+00:00","dateModified":"2026-02-10T02:53:36+00:00","description":"Sale of original comic art by Alex W. Inker. Original comic art from graphic novel Krimi, page 41.","breadcrumb":{"@id":"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/#primaryimage","url":"https:\/\/www.galeriebd.com\/wp-content\/uploads\/2025\/09\/Alex-inker-Krimi-dessins-originaux-bd-planche-41.jpg","contentUrl":"https:\/\/www.galeriebd.com\/wp-content\/uploads\/2025\/09\/Alex-inker-Krimi-dessins-originaux-bd-planche-41.jpg","width":1353,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/www.galeriebd.com\/en\/product\/alex-w-inker\/krimi-page-41\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.galeriebd.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.galeriebd.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Unclassified","item":"https:\/\/www.galeriebd.com\/en\/categorie-produit\/unclassified\/"},{"@type":"ListItem","position":4,"name":"Krimi"}]},{"@type":"WebSite","@id":"https:\/\/www.galeriebd.com\/en\/#website","url":"https:\/\/www.galeriebd.com\/en\/","name":"La Galerie de la Bande Dessin\u00e9e","description":"Vente de dessins originaux et de planches de BD","publisher":{"@id":"https:\/\/www.galeriebd.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.galeriebd.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.galeriebd.com\/en\/#organization","name":"La Galerie de la Bande Dessin\u00e9e","url":"https:\/\/www.galeriebd.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.galeriebd.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.galeriebd.com\/wp-content\/uploads\/2022\/09\/GalerieBD-logo-RVB-3pos-e1664285120235.jpg","contentUrl":"https:\/\/www.galeriebd.com\/wp-content\/uploads\/2022\/09\/GalerieBD-logo-RVB-3pos-e1664285120235.jpg","width":1400,"height":812,"caption":"La Galerie de la Bande Dessin\u00e9e"},"image":{"@id":"https:\/\/www.galeriebd.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GaleriedelaBandeDessinee","https:\/\/x.com\/comicartfactory","https:\/\/www.instagram.com\/galeriebd\/","https:\/\/www.youtube.com\/channel\/UCN3x23zPeXNcd0zkbi5dPeg\/videos"]}]}},"_links":{"self":[{"href":"https:\/\/www.galeriebd.com\/en\/wp-json\/wp\/v2\/product\/60808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galeriebd.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.galeriebd.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.galeriebd.com\/en\/wp-json\/wp\/v2\/media\/60809"}],"wp:attachment":[{"href":"https:\/\/www.galeriebd.com\/en\/wp-json\/wp\/v2\/media?parent=60808"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.galeriebd.com\/en\/wp-json\/wp\/v2\/product_brand?post=60808"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.galeriebd.com\/en\/wp-json\/wp\/v2\/product_cat?post=60808"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.galeriebd.com\/en\/wp-json\/wp\/v2\/product_tag?post=60808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}